{"id":8058,"date":"2022-09-02T11:09:46","date_gmt":"2022-09-02T11:09:46","guid":{"rendered":"https:\/\/isfelevatorshop.de\/a-propos-de-nous\/"},"modified":"2025-12-31T03:19:54","modified_gmt":"2025-12-31T03:19:54","slug":"a-propos-de-nous","status":"publish","type":"page","link":"https:\/\/isfelevatorshop.de\/fr\/a-propos-de-nous\/","title":{"rendered":"\u00c0 propos de nous"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"8058\" class=\"elementor elementor-8058 elementor-275\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"wd-negative-gap elementor-section elementor-top-section elementor-element elementor-element-e2a0fab elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e2a0fab\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-97078bc\" data-id=\"97078bc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-015b07a wd-width-100 elementor-widget elementor-widget-wd_title\" data-id=\"015b07a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"title-wrapper wd-set-mb reset-last-child wd-title-color-default wd-title-style-default wd-title-size-large text-left\">\n\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h1 class=\"woodmart-title-container title wd-fontsize-xxl\">D\u00e9couvrez la boutique en ligne d'ISF Elevator GmbH<\/h1> \n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b08f08b elementor-widget elementor-widget-wd_text_block\" data-id=\"b08f08b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_text_block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"wd-text-block reset-last-child text-left\">\n\t\t\t\n\t\t\t<p>Bienvenue chez <strong>ISF Elevator Shop<\/strong>, une r\u00e9f\u00e9rence d'excellence industrielle dans le domaine des ascenseurs et des composants de levage. \u00c9tablis avec la mission de fournir des \u00e9quipements d'ascenseurs in\u00e9gal\u00e9s, nous faisons progresser l'industrie depuis plus de 50 ans. Notre parcours a d\u00e9but\u00e9 en 1973 sous le nom de Uzay Teknik Cooperation \u00e0 Istanbul. Au fil de notre \u00e9volution et de notre ouverture sur les horizons mondiaux, nous avons chang\u00e9 de nom pour devenir <strong>ISF Elevator GmbH<\/strong> and Engineering Company.   <\/p>\n<p>Notre expertise ne r\u00e9side pas seulement dans la fourniture de composants d'ascenseurs ; il s'agit de partager l'art et la science qui sous-tendent le transport vertical. Nous pr\u00e9sentons avec fiert\u00e9 les produits Arkel de pointe, notamment des contr\u00f4leurs d'ascenseur avanc\u00e9s, des tableaux de commande d'ascenseur, ainsi que des unit\u00e9s de commande et des cartes sp\u00e9cialis\u00e9es telles que Adrive, Arcode, ARL-300 et ARL-500. Chaque produit que nous proposons est un t\u00e9moignage de notre engagement envers la qualit\u00e9, l'innovation et le monde complexe des ascenseurs.  <\/p>\n<p>Pour en savoir plus sur les d\u00e9tails de notre entreprise, y compris les adresses, les coordonn\u00e9es et le num\u00e9ro d'identification TVA, veuillez consulter notre section <a title=\"Mentions l\u00e9gales de ISF Elevator Shop\" href=\"https:\/\/isfelevatorshop.de\/fr\/mentions-legales\/\" target=\"_blank\" rel=\"noopener\">Mentions L\u00e9gales<\/a>. Nous accordons \u00e9galement une priorit\u00e9 absolue \u00e0 la confidentialit\u00e9 des donn\u00e9es, en veillant \u00e0 ce que vos informations soient trait\u00e9es avec le plus grand soin. Pour en savoir plus sur nos pratiques en mati\u00e8re de protection des donn\u00e9es, consultez notre <a title=\"Politique de confidentialit\u00e9\" href=\"https:\/\/isfelevatorshop.de\/fr\/politique-de-confidentialite\/\" target=\"_blank\" rel=\"noopener\">Politique de Confidentialit\u00e9<\/a>.  <\/p>\n<p>Pour d'autres informations, vous pouvez consulter la page <a title=\"Page de contact ISF Elevator Shop\" href=\"https:\/\/isfelevatorshop.de\/fr\/contactez-nous\/\" target=\"_blank\" rel=\"noopener\">Contact<\/a>.<\/p>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5909345\" data-id=\"5909345\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0b6f6de wd-video-theme-style elementor-widget elementor-widget-video\" data-id=\"0b6f6de\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=kDbE-BSr-cw&quot;,&quot;show_image_overlay&quot;:&quot;yes&quot;,&quot;image_overlay&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/isfelevatorshop.de\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/ISF-Elevator-Vintage-LOP-Europa-1.png&quot;,&quot;id&quot;:8056,&quot;size&quot;:&quot;&quot;,&quot;alt&quot;:&quot;ISF Elevator Vintage LOP Europa (1)&quot;,&quot;source&quot;:&quot;library&quot;},&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t\t\t<div class=\"elementor-custom-embed-image-overlay\" style=\"background-image: url(https:\/\/isfelevatorshop.de\/wp-content\/uploads\/2023\/08\/ISF-Elevator-Vintage-LOP-Europa-1.png);\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-custom-embed-play\" role=\"button\" aria-label=\"Lire la vid\u00e9o sur ISF Elevator Vintage LOP Europa (1)\" tabindex=\"0\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-play\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"wd-negative-gap elementor-section elementor-top-section elementor-element elementor-element-e5a03a3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e5a03a3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-eb34e00\" data-id=\"eb34e00\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-17d4268 wd-width-100 elementor-widget elementor-widget-wd_title\" data-id=\"17d4268\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"title-wrapper wd-set-mb reset-last-child wd-title-color-default wd-title-style-default wd-title-size-medium text-left\">\n\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h2 class=\"woodmart-title-container title wd-fontsize-xl\">Ce que l'on dit de nous<\/h2> \n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2fc1584 elementor-widget__width-initial elementor-widget elementor-widget-wd_testimonials\" data-id=\"2fc1584\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_testimonials.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"testimonials testimon-style-info-top  color-scheme- wd-carousel-container\" id=\"carousel-6845\">\n\t\t\t\t\t\t\t<div class=\"wd-carousel-inner\">\n\t\t\t\n\t\t\t<div class=\"wd-carousel wd-grid\" data-scroll_per_page=\"yes\" style=\"--wd-col-lg:1;--wd-col-md:1;--wd-col-sm:1;--wd-gap-lg:20px;--wd-gap-sm:10px;\">\n\t\t\t\t\t\t\t\t\t<div class=\"wd-carousel-wrap\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n<div class=\"wd-testimon wd-carousel-item\">\n\t<div class=\"wd-testimon-info\">\n\t\t\t\t\t<div class=\"wd-testimon-thumb\">\n\t\t\t\t<img decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/isfelevatorshop.de\/wp-content\/uploads\/2023\/08\/man-1-100x100.png\" class=\"testimonial-avatar-image\" alt=\"icon Man J.M\" srcset=\"https:\/\/isfelevatorshop.de\/wp-content\/uploads\/2023\/08\/man-1.png 100w, https:\/\/isfelevatorshop.de\/wp-content\/uploads\/2023\/08\/man-1-30x30.png 30w\" sizes=\"(max-width: 100px) 100vw, 100px\" \/>\t\t\t<\/div>\n\t\t\n\t\t<div class=\"wd-testimon-bio\">\n\t\t\t\t\t\t\t<div class=\"wd-testimon-name title\">\n\t\t\t\t\tJ. M.\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"wd-testimon-pos\">\n\t\t\t\t\tClient\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"star-rating\">\n\t\t\t\t<span style=\"width:100%\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t\t\t<div class=\"wd-testimon-text reset-last-child\">\n\t\t\t<p>J'ai achet\u00e9 une carte de commande d'ascenseur chez ISF Elevator Shop, et elle fonctionne exceptionnellement bien ! Leur \u00e9quipe technique m'a assist\u00e9 pour l'installation et la configuration, et j'ai r\u00e9ussi \u00e0 moderniser mon ascenseur sans aucun probl\u00e8me. Le support client \u00e9tait de premier ordre et j'ai b\u00e9n\u00e9fici\u00e9 d'un service professionnel tout au long du processus. Merci, ISF Elevator Shop   <\/p>\t\t<\/div>\n\t<\/div>\t\t\t\t\t\t\t\t\t\n<div class=\"wd-testimon wd-carousel-item\">\n\t<div class=\"wd-testimon-info\">\n\t\t\t\t\t<div class=\"wd-testimon-thumb\">\n\t\t\t\t<img decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/isfelevatorshop.de\/wp-content\/uploads\/2023\/08\/man-1-100x100.png\" class=\"testimonial-avatar-image\" alt=\"icon Man J.M\" srcset=\"https:\/\/isfelevatorshop.de\/wp-content\/uploads\/2023\/08\/man-1.png 100w, https:\/\/isfelevatorshop.de\/wp-content\/uploads\/2023\/08\/man-1-30x30.png 30w\" sizes=\"(max-width: 100px) 100vw, 100px\" \/>\t\t\t<\/div>\n\t\t\n\t\t<div class=\"wd-testimon-bio\">\n\t\t\t\t\t\t\t<div class=\"wd-testimon-name title\">\n\t\t\t\t\tMichael W.\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"wd-testimon-pos\">\n\t\t\t\t\tClient\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"star-rating\">\n\t\t\t\t<span style=\"width:100%\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t\t\t<div class=\"wd-testimon-text reset-last-child\">\n\t\t\t<p>J'ai achet\u00e9 des pi\u00e8ces de rechange pour mon ascenseur chez ISF Elevator Shop, et je ne pourrais pas \u00eatre plus satisfait de mon exp\u00e9rience. Ils proposent des mat\u00e9riaux de haute qualit\u00e9 \u00e0 des prix raisonnables, et ma commande a \u00e9t\u00e9 livr\u00e9e rapidement. L'\u00e9quipe de support technique a \u00e9galement \u00e9t\u00e9 prompte \u00e0 r\u00e9pondre \u00e0 mes questions. Je suis ravi d'avoir choisi ISF Elevator Shop et je les recommanderais \u00e0 tout le monde.   <\/p>\t\t<\/div>\n\t<\/div>\t\t\t\t\t\t\t\t\t\n<div class=\"wd-testimon wd-carousel-item\">\n\t<div class=\"wd-testimon-info\">\n\t\t\t\t\t<div class=\"wd-testimon-thumb\">\n\t\t\t\t<img decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/isfelevatorshop.de\/wp-content\/uploads\/2023\/08\/woman-Sarah-A-100x100.png\" class=\"testimonial-avatar-image\" alt=\"icon woman (Sarah A.)\" srcset=\"https:\/\/isfelevatorshop.de\/wp-content\/uploads\/2023\/08\/woman-Sarah-A.png 100w, https:\/\/isfelevatorshop.de\/wp-content\/uploads\/2023\/08\/woman-Sarah-A-30x30.png 30w\" sizes=\"(max-width: 100px) 100vw, 100px\" \/>\t\t\t<\/div>\n\t\t\n\t\t<div class=\"wd-testimon-bio\">\n\t\t\t\t\t\t\t<div class=\"wd-testimon-name title\">\n\t\t\t\t\tS. A.\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"wd-testimon-pos\">\n\t\t\t\t\tClient\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"star-rating\">\n\t\t\t\t<span style=\"width:100%\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t\t\t<div class=\"wd-testimon-text reset-last-child\">\n\t\t\t<p>Nous avons achet\u00e9 le moteur et les engrenages n\u00e9cessaires pour nos escaliers m\u00e9caniques chez ISF Elevator Shop. La qualit\u00e9 des produits est excellente, et d\u00e9sormais notre ascenseur fonctionne de mani\u00e8re beaucoup plus silencieuse et efficace. Je tiens \u00e0 remercier tout particuli\u00e8rement l'\u00e9quipe du support client ; ils nous ont offert une exp\u00e9rience fluide et se sont surpass\u00e9s pour r\u00e9pondre \u00e0 nos besoins. Vous pouvez faire vos achats en toute confiance chez ISF Elevator Shop !   <\/p>\t\t<\/div>\n\t<\/div>\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-nav-arrows wd-pos-sep wd-hover-1 wd-icon-1\">\n\t\t\t<div class=\"wd-btn-arrow wd-prev wd-disabled\">\n\t\t\t\t<div class=\"wd-arrow-inner\"><\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"wd-btn-arrow wd-next\">\n\t\t\t\t<div class=\"wd-arrow-inner\"><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d401353 wd-width-100 elementor-widget elementor-widget-wd_title\" data-id=\"d401353\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"title-wrapper wd-set-mb reset-last-child wd-title-color-default wd-title-style-default wd-title-size-medium text-left\">\n\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h2 class=\"woodmart-title-container title wd-fontsize-xl\">\u00c0 qui nous nous adressons<\/h2> \n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fa19cb7 elementor-widget__width-initial elementor-widget elementor-widget-wd_text_block\" data-id=\"fa19cb7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_text_block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"wd-text-block reset-last-child text-left\">\n\t\t\t\n\t\t\t<div id=\"attachment_8052\" style=\"width: 2570px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" aria-describedby=\"caption-attachment-8052\" src=\"https:\/\/isfelevatorshop.de\/wp-content\/uploads\/2023\/08\/An-elevator-moving-outside-a-skyscraper-scaled.jpg\" alt=\"Un ascenseur se d\u00e9pla\u00e7ant \u00e0 l'ext\u00e9rieur d'un gratte-ciel\" width=\"2560\" height=\"2560\"><p id=\"caption-attachment-8052\" class=\"wp-caption-text\">Avancez sur le balcon aux parois de verre d'un gratte-ciel imposant et immergez-vous dans la beaut\u00e9 grandiose du paysage urbain. Depuis cette plateforme sur\u00e9lev\u00e9e, vous profiterez d'une vue imprenable et \u00e9poustouflante sur la ville en contrebas.<\/p><\/div>\n<p>ISF Elevator Shop est fier de servir une client\u00e8le diversifi\u00e9e, offrant des solutions compl\u00e8tes pour les cartes de commande, les mat\u00e9riaux et les \u00e9quipements d'ascenseurs. Nos partenariats s'\u00e9tendent aux propri\u00e9taires de b\u00e2timents, aux gestionnaires immobiliers, aux entreprises de construction, aux architectes, aux concepteurs et aux gestionnaires d'installations. Gr\u00e2ce \u00e0 notre vaste gamme de composants d'ascenseurs, incluant les produits renomm\u00e9s Arkel, nous garantissons des performances optimales, une esth\u00e9tique soign\u00e9e et une s\u00e9curit\u00e9 maximale dans chaque projet.  <\/p>\n<h3>Port\u00e9e mondiale<\/h3>\n<p>Nos produits sont disponibles dans toute l'Europe : <span style=\"font-size: 14px;\">Autriche, Belgique, Bulgarie, Croatie, Chypre, R\u00e9publique tch\u00e8que, Danemark, Estonie, Finlande, France, Allemagne, Gr\u00e8ce, Hongrie, Irlande, Italie, Lettonie, Lituanie, Luxembourg, Malte, Pays-Bas, Pologne, Portugal, Roumanie, Slovaquie, Slov\u00e9nie, Espagne et Su\u00e8de.<\/span><\/p>\n<ul>\n<\/ul>\n<h3>Options de langue<\/h3>\n<p>Nous communiquons avec nos clients en anglais, en allemand et en turc.<\/p>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-23d54c5\" data-id=\"23d54c5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e628c2a wd-width-100 elementor-widget elementor-widget-wd_title\" data-id=\"e628c2a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"title-wrapper wd-set-mb reset-last-child wd-title-color-default wd-title-style-default wd-title-size-medium text-left\">\n\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h2 class=\"woodmart-title-container title wd-fontsize-xl\">Nous communiquons avec nos clients en anglais, en allemand et en turc.<\/h2> \n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b2b668d elementor-widget elementor-widget-wd_text_block\" data-id=\"b2b668d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_text_block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"wd-text-block reset-last-child text-left\">\n\t\t\t\n\t\t\t<p><\/p>\n<p class=\"wp-block-paragraph\"><img decoding=\"async\" class=\"aligncenter wp-image-1781 size-full\" src=\"https:\/\/isfelevatorshop.de\/wp-content\/uploads\/2023\/08\/elevator-lift-button-scaled.jpg\" alt=\"Une main appuie sur le bouton de l'ascenseur.\" width=\"2560\" height=\"2560\" srcset=\"https:\/\/isfelevatorshop.de\/wp-content\/uploads\/2023\/08\/elevator-lift-button-scaled.jpg 2560w, https:\/\/isfelevatorshop.de\/wp-content\/uploads\/2023\/08\/elevator-lift-button-scaled-600x600.jpg 600w, https:\/\/isfelevatorshop.de\/wp-content\/uploads\/2023\/08\/elevator-lift-button-scaled-30x30.jpg 30w, https:\/\/isfelevatorshop.de\/wp-content\/uploads\/2023\/08\/elevator-lift-button-1200x1200.jpg 1200w, https:\/\/isfelevatorshop.de\/wp-content\/uploads\/2023\/08\/elevator-lift-button-300x300.jpg 300w, https:\/\/isfelevatorshop.de\/wp-content\/uploads\/2023\/08\/elevator-lift-button-1024x1024.jpg 1024w, https:\/\/isfelevatorshop.de\/wp-content\/uploads\/2023\/08\/elevator-lift-button-150x150.jpg 150w, https:\/\/isfelevatorshop.de\/wp-content\/uploads\/2023\/08\/elevator-lift-button-768x768.jpg 768w, https:\/\/isfelevatorshop.de\/wp-content\/uploads\/2023\/08\/elevator-lift-button-1536x1536.jpg 1536w, https:\/\/isfelevatorshop.de\/wp-content\/uploads\/2023\/08\/elevator-lift-button-2048x2048.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/p>\n<p>Une main appuie sur le bouton de l'ascenseur.  <\/p>\n<p><\/p>\n<p><!-- \/wp:list --><\/p>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-75380a4 wd-width-100 elementor-widget elementor-widget-wd_title\" data-id=\"75380a4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"title-wrapper wd-set-mb reset-last-child wd-title-color-default wd-title-style-default wd-title-size-medium text-left\">\n\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h2 class=\"woodmart-title-container title wd-fontsize-xl\">Notre vision<\/h2> \n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7d6880b elementor-widget elementor-widget-wd_text_block\" data-id=\"7d6880b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_text_block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"wd-text-block reset-last-child text-left\">\n\t\t\t\n\t\t\t<p><!-- wp:paragraph --><\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-1790 size-full\" src=\"https:\/\/isfelevatorshop.de\/wp-content\/uploads\/2023\/08\/elevator-in-a-skyscraper.png\" alt=\"on envisage des ascenseurs \u00e0 la pointe de la technologie\" width=\"700\" height=\"452\" srcset=\"https:\/\/isfelevatorshop.de\/wp-content\/uploads\/2023\/08\/elevator-in-a-skyscraper.png 700w, https:\/\/isfelevatorshop.de\/wp-content\/uploads\/2023\/08\/elevator-in-a-skyscraper-30x19.png 30w, https:\/\/isfelevatorshop.de\/wp-content\/uploads\/2023\/08\/elevator-in-a-skyscraper-600x387.png 600w, https:\/\/isfelevatorshop.de\/wp-content\/uploads\/2023\/08\/elevator-in-a-skyscraper-300x194.png 300w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/p>\n<p>nous envisageons des ascenseurs \u00e0 la pointe de la technologie  <\/p>\n<p><!-- \/wp:paragraph --><\/p>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"wd-negative-gap elementor-element elementor-element-39b0ecd e-flex e-con-boxed e-con e-parent\" data-id=\"39b0ecd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f2f2659 wd-width-100 elementor-widget elementor-widget-wd_title\" data-id=\"f2f2659\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"title-wrapper wd-set-mb reset-last-child wd-title-color-default wd-title-style-default wd-title-size-medium text-left\">\n\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h2 class=\"woodmart-title-container title wd-fontsize-xl\">Nos produits et services<\/h2> \n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dbde668 elementor-widget elementor-widget-wd_text_block\" data-id=\"dbde668\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_text_block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"wd-text-block reset-last-child text-left\">\n\t\t\t\n\t\t\t<p>Bienvenue au c\u0153ur de ISF Elevator Shop, o\u00f9 l'innovation rencontre la fonctionnalit\u00e9. Gr\u00e2ce \u00e0 un vaste entrep\u00f4t situ\u00e9 en Allemagne, nous sommes pr\u00eats \u00e0 approvisionner les entreprises d'ascenseurs du monde entier, en nous concentrant principalement sur l'Europe. Notre catalogue num\u00e9rique compte plus de 1 000 pi\u00e8ces de rechange pour ascenseurs et escaliers m\u00e9caniques. Voici un aper\u00e7u de nos offres :   <\/p>\n<ul>\n<li><strong>Armoires de commande &amp; Tableaux d'ascenseur :<\/strong> L'\u00e9pine dorsale de tout syst\u00e8me d'ascenseur, garantissant un fonctionnement fluide.<\/li>\n<li><strong>Produits Sp\u00e9cialis\u00e9s Arkel :<\/strong> Plongez dans l'univers d'Adrive, Arcode, ARL-300 et ARL-500, repr\u00e9sentant le summum des unit\u00e9s et cartes de commande d'ascenseur.<\/li>\n<li><strong>Filtres CEM &amp; R\u00e9sistances de freinage :<\/strong> Composants essentiels garantissant la s\u00e9curit\u00e9 et r\u00e9duisant les interf\u00e9rences \u00e9lectromagn\u00e9tiques.<\/li>\n<li><strong>Syst\u00e8mes IoT &amp; Indicateurs LCD :<\/strong> Solutions modernes pour la surveillance en temps r\u00e9el et des fonctionnalit\u00e9s d'affichage claires.<\/li>\n<li><strong>S\u00e9rie Arcode :<\/strong> Des unit\u00e9s p\u00e9riph\u00e9riques aux unit\u00e9s d'appel palier et indicateurs, nous couvrons tous vos besoins Arcode.<\/li>\n<li><strong>Solutions de S\u00e9curit\u00e9 et d'Alimentation :<\/strong> Comprenant des barri\u00e8res photo\u00e9lectriques, des cartes de contr\u00f4le de porte, des batteries, des UPS et plus encore pour garantir des op\u00e9rations ininterrompues et s\u00fbres.<\/li>\n<li><strong>Composants Additionnels :<\/strong> Qu'il s'agisse d'accessoires EN 81-20, de cartes de circuits imprim\u00e9s ou de guides de porte, notre vaste gamme r\u00e9pond \u00e0 tous les besoins en mati\u00e8re d'ascenseurs.<\/li>\n<\/ul>\n<p>Notre engagement envers la qualit\u00e9, l'innovation et un service client in\u00e9gal\u00e9 a consolid\u00e9 notre r\u00e9putation en tant que nom de confiance dans l'industrie de l'ascenseur. Explorez notre site web, passez commande et b\u00e9n\u00e9ficiez de livraisons rapides, souvent d\u00e8s le lendemain <\/p>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"wd-negative-gap elementor-element elementor-element-7c9e970 e-flex e-con-boxed e-con e-parent\" data-id=\"7c9e970\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-933fddd wd-width-100 elementor-widget elementor-widget-wd_title\" data-id=\"933fddd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"title-wrapper wd-set-mb reset-last-child wd-title-color-default wd-title-style-default wd-title-size-medium text-left\">\n\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h2 class=\"woodmart-title-container title wd-fontsize-xl\">FAQ<\/h2> \n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-55f6e37 elementor-widget elementor-widget-wd_text_block\" data-id=\"55f6e37\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_text_block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"wd-text-block reset-last-child text-left\">\n\t\t\t\n\t\t\t<h3><strong><img decoding=\"async\" class=\"aligncenter wp-image-5477 size-medium\" src=\"https:\/\/isfelevatorshop.de\/wp-content\/uploads\/2023\/10\/ISF-Elevator-GmbH-Shops-FAQ-300x169.png\" alt=\"FAQ (foire aux questions) de la boutique ISF Elevator GmbH\" width=\"300\" height=\"169\" srcset=\"https:\/\/isfelevatorshop.de\/wp-content\/uploads\/2023\/10\/ISF-Elevator-GmbH-Shops-FAQ-300x169.png 300w, https:\/\/isfelevatorshop.de\/wp-content\/uploads\/2023\/10\/ISF-Elevator-GmbH-Shops-FAQ-768x432.png 768w, https:\/\/isfelevatorshop.de\/wp-content\/uploads\/2023\/10\/ISF-Elevator-GmbH-Shops-FAQ-30x17.png 30w, https:\/\/isfelevatorshop.de\/wp-content\/uploads\/2023\/10\/ISF-Elevator-GmbH-Shops-FAQ.png 960w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>Quand ISF Elevator Shop a-t-elle \u00e9t\u00e9 cr\u00e9\u00e9e et quelles sont ses origines ?<\/strong><\/h3>\n<p>ISF Elevator Shop b\u00e9n\u00e9ficie de plus d'un demi-si\u00e8cle d'expertise, avec des racines solidement ancr\u00e9es en 1973. Initialement fond\u00e9e sous le nom de \u00ab Uzay Teknik Cooperation \u00bb dans la ville dynamique d'Istanbul, l'entreprise a subi une transformation, devenant ISF Elevator and Engineering Company. Ce changement n'\u00e9tait pas seulement nominal ; il a marqu\u00e9 notre \u00e9volution vers une puissance mondiale dans l'industrie de l'ascenseur.  <\/p>\n<h3><strong>\u00c0 qui s'adresse ISF Elevator Shop ?<\/strong><\/h3>\n<p>Notre client\u00e8le est aussi diversifi\u00e9e que notre gamme de produits. Nous sommes fiers de r\u00e9pondre aux besoins des propri\u00e9taires d'immeubles, des gestionnaires immobiliers, des magnats de la construction, des entrepreneurs, des architectes visionnaires, des concepteurs innovants et des gestionnaires d'installations diligents. Notre mission ? Fournir des solutions compl\u00e8tes adapt\u00e9es \u00e0 chaque besoin en mati\u00e8re de cartes de commande, de mat\u00e9riaux et d'\u00e9quipements d'ascenseur.   <\/p>\n<h3><strong>Quelle est l'expertise principale d'ISF Elevator Shop ?<\/strong><\/h3>\n<p>Au c\u0153ur d'ISF Elevator Shop se trouve une passion pour la conception de syst\u00e8mes d'ascenseurs. Nous ne sommes pas seulement des fournisseurs ; nous sommes des innovateurs. De la fourniture de chaque composant et pi\u00e8ce de rechange imaginable \u00e0 l'assurance que nos clients re\u00e7oivent un support in\u00e9gal\u00e9, notre d\u00e9vouement est in\u00e9branlable. Nous canalisons notre vaste exp\u00e9rience de l'industrie dans l'\u00e9laboration de solutions d'ascenseurs de pointe.   <\/p>\n<h3><strong>Quelle est la vision d'ISF Elevator Shop ?<\/strong><\/h3>\n<p>Nos objectifs sont tourn\u00e9s vers une reconnaissance mondiale. ISF Elevator Shop se con\u00e7oit comme le phare de l'industrie de l'ascenseur. Comment pr\u00e9voyons-nous d'y parvenir ? En fournissant syst\u00e9matiquement des syst\u00e8mes d'ascenseurs innovants, int\u00e9gr\u00e9s et flexibles. En d\u00e9passant les attentes des clients \u00e0 chaque \u00e9tape. En forgeant des partenariats durables, en d\u00e9fendant des pratiques durables et en restant toujours \u00e0 la pointe des avanc\u00e9es technologiques.     <\/p>\n<h3><strong>Quels produits et services ISF Elevator Shop propose-t-il ?<\/strong><\/h3>\n<p>ISF Elevator Shop est plus qu'un simple fournisseur ; c'est une plaque tournante pour tout ce qui concerne les ascenseurs et les escaliers m\u00e9caniques. Bas\u00e9 en Allemagne, notre vaste entrep\u00f4t facilite l'approvisionnement des entreprises d'ascenseurs \u00e0 travers le monde, avec un accent particulier sur l'Europe. Notre liste de produits est \u00e9tendue, comprenant plus de 1 000 pi\u00e8ces de rechange pour ascenseurs, des contr\u00f4leurs d'ascenseur et armoires de commande aux articles sp\u00e9cialis\u00e9s tels que le variateur VVVF Arkel ADrive, les filtres CEM et les indicateurs LCD. Au-del\u00e0 des produits, notre engagement envers un service exceptionnel garantit que nos clients ont toujours acc\u00e8s au meilleur des pi\u00e8ces de rechange pour ascenseurs et escaliers m\u00e9caniques.   <\/p>\n<h2>Contactez-nous<\/h2>\n<ol>\n<li><strong>Adresse Mainaschaff :<\/strong> \ud83d\udea9 Raiffeisenstr. 8, 63814 Mainaschaff \/ Allemagne <\/li>\n<li><strong>T\u00e9l\u00e9phone :<\/strong> \ud83d\udcde <a title=\"ISF Elevator Shop T\u00e9l.\" href=\"tel:+4915758828410\" target=\"_blank\" rel=\"noopener\">+49 157 58828410<\/a><\/li>\n<li><strong>E-mail :<\/strong> \ud83d\udce7 <a href=\"mailto:info@isfelevatorshop.de\" target=\"_new\">info@isfelevatorshop.de<\/a><\/li>\n<li><strong>WhatsApp :<\/strong> \ud83d\udcf1 <a href=\"https:\/\/wa.me\/4915758828410\" target=\"_new\" rel=\"nofollow noopener\">Contact WhatsApp<\/a><\/li>\n<li><strong>Instagram:<\/strong> \ud83d\udcf8 <a href=\"https:\/\/www.instagram.com\/isfelevatorshop\/\" target=\"_new\" rel=\"nofollow noopener\">Instagram ISF Elevator Shop<\/a><\/li>\n<li><strong>Site Web :<\/strong> \ud83c\udf10 <a href=\"https:\/\/isfelevatorshop.de\/fr\/\" target=\"_new\">ISF Elevator Shop<\/a><\/li>\n<\/ol>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>D\u00e9couvrez la boutique en ligne d&rsquo;ISF Elevator GmbH Bienvenue chez ISF Elevator Shop, une r\u00e9f\u00e9rence d&rsquo;excellence industrielle dans le domaine<\/p>\n","protected":false},"author":2,"featured_media":8057,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-8058","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/isfelevatorshop.de\/fr\/wp-json\/wp\/v2\/pages\/8058","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/isfelevatorshop.de\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/isfelevatorshop.de\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/isfelevatorshop.de\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/isfelevatorshop.de\/fr\/wp-json\/wp\/v2\/comments?post=8058"}],"version-history":[{"count":5,"href":"https:\/\/isfelevatorshop.de\/fr\/wp-json\/wp\/v2\/pages\/8058\/revisions"}],"predecessor-version":[{"id":8657,"href":"https:\/\/isfelevatorshop.de\/fr\/wp-json\/wp\/v2\/pages\/8058\/revisions\/8657"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/isfelevatorshop.de\/fr\/wp-json\/wp\/v2\/media\/8057"}],"wp:attachment":[{"href":"https:\/\/isfelevatorshop.de\/fr\/wp-json\/wp\/v2\/media?parent=8058"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}